{"id":1329,"date":"2025-11-09T23:45:46","date_gmt":"2025-11-09T21:45:46","guid":{"rendered":"https:\/\/gruene-wiesbaden.de\/?p=1329"},"modified":"2026-04-09T00:09:17","modified_gmt":"2026-04-08T22:09:17","slug":"wohnen","status":"publish","type":"post","link":"https:\/\/gruene-wiesbaden.de\/fr\/wohnen\/","title":{"rendered":"Logement"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium with_img\"><div class=\"l-section-img\" role=\"img\" data-img-width=\"1080\" data-img-height=\"800\" style=\"background-image: url(https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/neuer-Verlauf-gruene-wiesbaden.de_-2-e1762709402177.png);\"><\/div><div class=\"l-section-overlay\" style=\"background:var(--color-header-top-transparent-bg)\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><h1 class=\"w-post-elm post_title us_custom_a574d586 has_text_color entry-title\">Logement<\/h1><div class=\"g-cols wpb_row via_grid cols_2-1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_8b3d6790 has_text_color\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Le logement est un droit de l'homme et un besoin \u00e9l\u00e9mentaire des gens. Une offre de logements abordables pour tous, de bonne qualit\u00e9 et en quantit\u00e9 suffisante, doit donc \u00eatre l'objectif de la politique du logement. Wiesbaden souffre \u00e9galement d'une grave p\u00e9nurie de logements abordables, tandis que l'augmentation des loyers et des prix des terrains aggrave les divisions sociales. C'est pourquoi nous avons besoin \u00e0 Wiesbaden d'un secteur du logement fort, orient\u00e9 vers le bien commun, dans lequel les logements sont socialement li\u00e9s de mani\u00e8re permanente. Dans le m\u00eame temps, il faut construire de mani\u00e8re neutre sur le plan climatique et \u00e9conome en surface afin de laisser aux g\u00e9n\u00e9rations futures une ville habitable.<\/span><\/p>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn us-btn-style_8 icon_atleft\" href=\"https:\/\/gruene-wiesbaden.de\/fr\/kommunalwahl\/#Kapitel1\"><i class=\"fas fa-chevron-circle-right\"><\/i><span class=\"w-btn-label\">Retour \u00e0 la vue d'ensemble<\/span><\/a><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"2560\" height=\"1920\" src=\"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.6-Wohnen-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.6-Wohnen-scaled.jpg 2560w, https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.6-Wohnen-400x300.jpg 400w, https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.6-Wohnen-600x450.jpg 600w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h1>Ce qu'une bonne politique du logement signifie pour nous<\/h1>\n<\/div><\/div><div class=\"w-separator size_large\"><\/div><div class=\"g-cols wpb_row via_grid cols_3 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-middle-bg);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Cr\u00e9er un logement abordable<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">Un logement abordable est une condition essentielle pour une vie humaine dans la dignit\u00e9 et la libert\u00e9. Qu\u2019il s\u2019agisse de familles \u00e0 la recherche d\u2019un logement plus grand ou de personnes \u00e2g\u00e9es qui souhaitent r\u00e9duire leur taille, tout le monde doit pouvoir trouver un logement abordable. De plus, personne ne doit avoir peur de ne plus pouvoir payer l'appartement ou d'\u00eatre \u00e9vinc\u00e9.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-transparent-text);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Permettre de multiples formes d'habitation<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">Des modes de construction flexibles par diff\u00e9rents promoteurs de logements (en particulier les soci\u00e9t\u00e9s publiques de logement, les coop\u00e9ratives, les communaut\u00e9s de construction et les projets de logements collectifs) cr\u00e9ent les formes d'habitation qui correspondent aux diff\u00e9rents projets de vie et aux diff\u00e9rentes \u00e9tapes de la vie.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-transparent-text);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Orientation vers le bien commun<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">La politique urbaine du logement d'int\u00e9r\u00eat g\u00e9n\u00e9ral constitue un contrepoids durable \u00e0 la hausse des loyers et des prix des terrains ainsi qu'\u00e0 la maximisation des profits.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"g-cols wpb_row via_grid cols_3 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-middle-bg);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Renforcer une alimentation saine et r\u00e9gionale<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">Il est important pour nous que notre r\u00e9gion produise des aliments sains \u00e0 des prix abordables. Une bonne alimentation est la base d\u2019une vie active et agr\u00e9able pour nous, nos enfants et nos petits-enfants. Et ce, pour tous, et non comme le privil\u00e8ge de quelques-uns.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-transparent-text);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Construction peu encombrante<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">Le sol n'est pas reproductible. Le recompactage, en tenant compte des fonctions climatiques et de l'utilisation efficace des surfaces d\u00e9j\u00e0 scell\u00e9es, prot\u00e8ge nos ressources naturelles et l'environnement.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-transparent-text);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Neutralit\u00e9 climatique<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">Les \u00e9nergies renouvelables et les mat\u00e9riaux de construction durables permettent de construire des logements durables et climatiquement neutres. \u00c0 l'avenir, nous examinerons \u00e9galement le cycle de vie d'un b\u00e2timent et le bilan \u00e9cologique des mat\u00e9riaux de construction.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn us-btn-style_8 icon_atleft\" href=\"https:\/\/gruene-wiesbaden.de\/fr\/kommunalwahl\/#Kapitel1\"><i class=\"fas fa-chevron-circle-right\"><\/i><span class=\"w-btn-label\">Retour \u00e0 la vue d'ensemble<\/span><\/a><\/div><div class=\"w-separator size_medium\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto with_img\"><div class=\"l-section-img\" role=\"img\" data-img-width=\"2560\" data-img-height=\"1920\" style=\"background-image: url(https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.6-Wohnen-scaled.jpg);background-repeat: no-repeat;\"><\/div><div class=\"l-section-overlay\" style=\"background:var(--color-header-top-transparent-bg)\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default stacking_default\" style=\"--columns-gap:1rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-separator size_large\"><\/div><div class=\"wpb_text_column background_inside_text\"><div class=\"wpb_wrapper\"><h1>Ce que nous voulons concr\u00e8tement faire dans ce domaine<\/h1>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-tabs us_custom_42d693a0 has_text_color style_default switch_click accordion has_scrolling\" style=\"--sections-title-size:1.4rem\"><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section has_text_color\" id=\"x402\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-x402\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Cr\u00e9er et s\u00e9curiser des logements abordables<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-x402\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Beaucoup de gens ne peuvent plus se permettre un appartement \u00e0 Wiesbaden. C'est pourquoi nous voulons utiliser toutes les possibilit\u00e9s pour cr\u00e9er et garantir \u00e0 long terme des logements abordables, en particulier pour des raisons d'int\u00e9r\u00eat g\u00e9n\u00e9ral.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous avons veill\u00e9 \u00e0 ce qu'au cours de la derni\u00e8re l\u00e9gislature, la ville ait port\u00e9 \u00e0 40 % le taux d'engagement social pour les grands projets de construction urbaine et priv\u00e9e et nous voulons qu'elle le maintienne \u00e0 l'avenir. Nous avons \u00e9galement veill\u00e9 \u00e0 ce que les soci\u00e9t\u00e9s de construction de logements urbains GWW et GeWeGe prolongent le frein au loyer pour les loyers existants, de sorte que les augmentations de loyer restent nettement inf\u00e9rieures au plafond l\u00e9gal. Nous voulons ainsi \u00e9viter le refoulement et garantir des logements abordables \u00e0 long terme.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Gr\u00e2ce \u00e0 ces deux mesures, le niveau des loyers existants reste stable et, par cons\u00e9quent, le niveau des loyers. Le miroir des loyers montre \u00e0 quel point les loyers comparatifs usuels sont \u00e9lev\u00e9s. Il est \u00e9tabli r\u00e9guli\u00e8rement sur la base de nombreux contrats de location existants et veille \u00e0 ce que les loyers restent transparents et tra\u00e7ables.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous maintiendrons que les soci\u00e9t\u00e9s municipales ne louent en principe pas au-dessus de la moyenne dans le miroir locatif pour les nouvelles locations. En outre, nous soutenons les locataires dans les nouvelles locations en fournissant des informations et des conseils suppl\u00e9mentaires en plus du miroir de location afin d'am\u00e9liorer l'application du frein f\u00e9d\u00e9ral au loyer.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Nous maintenons les prescriptions de densit\u00e9 de la d\u00e9cision sur les terrains \u00e0 b\u00e2tir: Pour les nouvelles zones \u00e0 b\u00e2tir, au moins 80 unit\u00e9s d'habitation par hectare sont pr\u00e9vues, \u00e0 l'exception de 50 unit\u00e9s d'habitation dans les banlieues rurales, pour autant que le caract\u00e8re local soit pr\u00e9serv\u00e9.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">En outre, nous voulons continuer \u00e0 soutenir la construction d'appartements d'apprentis et d'entreprises ainsi que de r\u00e9sidences \u00e9tudiantes.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"y54f\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-y54f\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Mettre le plus de terrain possible entre les mains de la ville<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-y54f\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Le sol est un bien rare et non reproductible qui ne peut \u00eatre soumis au seul march\u00e9. En revanche, une politique fonci\u00e8re active, telle que celle que nous, les VERTS, avons promue \u00e0 Wiesbaden, est un instrument strat\u00e9gique efficace qui permet \u00e0 la commune de jouer un r\u00f4le d'acteur: Elle ach\u00e8te, g\u00e8re et distribue des terrains de mani\u00e8re cibl\u00e9e.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">L'acquisition pr\u00e9coce d'espaces de d\u00e9veloppement potentiels pour les zones urbaines, les agglom\u00e9rations et les espaces ouverts est le fondement du d\u00e9veloppement urbain, sert les services d'int\u00e9r\u00eat g\u00e9n\u00e9ral pour les citoyens et permet aux municipalit\u00e9s d'accro\u00eetre leur influence sur le march\u00e9 local du logement. La commune peut d\u00e9cider \u00e0 qui elle c\u00e8de des biens immobiliers ou des terres. Ce n'est qu'ainsi que la sp\u00e9culation sur le sol peut \u00eatre \u00e9vit\u00e9e par des tiers et que la construction de logements \u00e0 bas prix peut \u00eatre r\u00e9alis\u00e9e. La commune peut d\u00e9cider de d\u00e9velopper des logements, des infrastructures sociales sous forme de cr\u00e8ches ou d'\u00e9coles ou de promouvoir la protection de l'environnement et du climat. Une politique fonci\u00e8re active renforce ainsi la capacit\u00e9 d'action des communes.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La politique fonci\u00e8re doit \u00eatre planifi\u00e9e activement et \u00e0 long terme afin de mettre en \u0153uvre les objectifs d'int\u00e9r\u00eat g\u00e9n\u00e9ral de la commune. Nous voulons poursuivre cette strat\u00e9gie. Nous empruntons ainsi une voie que des villes comme Ulm, M\u00fcnster et Hambourg empruntent avec succ\u00e8s depuis des d\u00e9cennies.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"c66a\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-c66a\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Utiliser le droit d'emphyt\u00e9ose<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-c66a\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nous misons de plus en plus sur le droit d'emphyt\u00e9ose lors de l'attribution de terrains \u00e0 b\u00e2tir afin de maintenir durablement les terrains entre les mains des communes. Le taux emphyt\u00e9otique de 1,0% (ou, le cas \u00e9ch\u00e9ant, moins) pour les initiatives particuli\u00e8rement \u00e9ligibles.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"v783\" style=\"background:var(--color-header-middle-bg);color:var(--color-content-heading);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-v783\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Promouvoir l'attribution de concepts et le logement collectif<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-v783\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nous voulons \u00e9tendre l'attribution des surfaces d'habitation selon le meilleur concept (attribution du concept). En promouvant le logement collectif, nous renfor\u00e7ons les quartiers et cr\u00e9ons des liens sociaux.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"n89f\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-n89f\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Exploiter le potentiel urbain<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-n89f\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nous voulons introduire un statut de vacance selon le droit du Land de Hesse et limiter la conversion en appartements de vacances. En outre, nous soutenons le recompactage et l'agrandissement afin de mieux utiliser l'espace disponible, de cr\u00e9er des logements suppl\u00e9mentaires et de r\u00e9duire le besoin de nouvelles zones d'habitation. Ainsi, nous voulons aborder activement les possibilit\u00e9s de construire des supermarch\u00e9s et des parkings et discuter avec les propri\u00e9taires.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"x9c7\" style=\"background:var(--color-header-middle-bg);color:var(--color-header-middle-text);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-x9c7\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Construire de mani\u00e8re durable<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-x9c7\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nous voulons une construction climatiquement neutre et \u00e9conome en surface avec des mat\u00e9riaux de construction \u00e9cologiques ainsi que des appartements accessibles et adapt\u00e9s \u00e0 l'\u00e2ge dans tous les nouveaux projets de construction. Cette construction prot\u00e8ge le climat, pr\u00e9serve les ressources naturelles et permet de cr\u00e9er des quartiers r\u00e9sidentiels o\u00f9 tous, jeunes ou moins jeunes, avec ou sans mobilit\u00e9 r\u00e9duite, peuvent bien vivre ensemble.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"oade\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-oade\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">D\u00e9velopper des quartiers verts<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-oade\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nous d\u00e9veloppons des quartiers durables avec une qualit\u00e9 de vie \u00e9lev\u00e9e (par exemple des salles d'exp\u00e9rimentation urbanistiques) et g\u00e9rons activement les stocks. La valorisation des quartiers am\u00e9liore la qualit\u00e9 de vie, renforce le sentiment de s\u00e9curit\u00e9 et favorise la coh\u00e9sion sociale dans les quartiers.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"ac07\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-ac07\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Soutenir les groupes vuln\u00e9rables<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-ac07\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nous nous engageons \u00e0 fournir des logements cibl\u00e9s aux femmes des foyers pour femmes afin de limiter la dur\u00e9e de s\u00e9jour dans ces foyers.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Il est important pour nous que la ville soutienne les gens de mani\u00e8re \u00e0 ce qu'ils ne tombent pas dans le sans-abrisme. Nous voulons surmonter le sans-abrisme avec l'approche du logement d'abord. Lorsque cela n'est pas possible ou souhait\u00e9 par les personnes concern\u00e9es, nous nous engageons pour suffisamment de places de couchage et de soins m\u00e9dicaux.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"cd28\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-cd28\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Ostfeld se d\u00e9veloppe durablement<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-cd28\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nous appliquons de mani\u00e8re cons\u00e9quente les crit\u00e8res d\u00e9cid\u00e9s en 2020 pour l'Ostfeld. Il s'agit notamment de logements socialement li\u00e9s, de la neutralit\u00e9 carbone dans l'entreprise, d'\u00e9nergies renouvelables et d'un quartier majoritairement sans voiture. Une connexion ferroviaire \u00e9ligible doit \u00eatre d\u00e9cid\u00e9e avant le d\u00e9but de la construction. Les \u00e9missions sonores des avions doivent faire l'objet d'un contr\u00f4le intensif et des mesures de protection appropri\u00e9es doivent \u00eatre mises en \u0153uvre.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"xe40\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-xe40\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Alliance pour le logement<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-xe40\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nous voulons impliquer activement les initiatives citoyennes, les coop\u00e9ratives, les conseils locaux et les propri\u00e9taires fonciers dans la planification du logement et examiner une agence immobili\u00e8re coop\u00e9rative en coop\u00e9ration avec les villes voisines. Cette mise en r\u00e9seau cr\u00e9e des solutions innovantes et renforce le bien commun dans la politique du logement.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn us-btn-style_8 icon_atleft\" href=\"https:\/\/gruene-wiesbaden.de\/fr\/kommunalwahl\/#Kapitel1\"><i class=\"fas fa-chevron-circle-right\"><\/i><span class=\"w-btn-label\">Retour \u00e0 la vue d'ensemble<\/span><\/a><\/div><div class=\"w-separator size_large\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h1>Ce que nous avons d\u00e9j\u00e0 accompli<\/h1>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-tabs us_custom_42d693a0 has_text_color style_default switch_click accordion has_scrolling\" style=\"--sections-title-size:1.4rem\"><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section has_text_color\" id=\"i297\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-i297\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Augmentation du taux d'aide au logement<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-i297\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nous, les VERTS, sommes parvenus \u00e0 augmenter la proportion de logements subventionn\u00e9s pour les revenus faibles et moyens dans les projets de construction de logements. 40 % s'appliquent aux soci\u00e9t\u00e9s urbaines, 30 % aux investisseurs priv\u00e9s \u00e0 partir de 40 unit\u00e9s d'habitation.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"a3b2\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-a3b2\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Frein de loyer<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-a3b2\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nous avons veill\u00e9 \u00e0 ce que le frein aux loyers urbains pour les locataires des soci\u00e9t\u00e9s de logement urbain GWW et GeWeGe, introduit en 2020, soit encore prolong\u00e9 et \u00e9tendu \u00e0 tous les logements librement financ\u00e9s du parc immobilier des deux soci\u00e9t\u00e9s.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"k4d0\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-k4d0\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Les statuts contre la vacance sp\u00e9culative<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-k4d0\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Le gouvernement du Land de Hesse a annonc\u00e9 en janvier 2025 l'adoption d'une loi contre l'inoccupation sp\u00e9culative. Il vise \u00e0 permettre aux municipalit\u00e9s aux march\u00e9s du logement tendus d'\u00e9tablir des statuts contre l'inoccupation sp\u00e9culative. Nous avons d\u00e9j\u00e0 charg\u00e9 notre administration de pr\u00e9parer un projet de statuts afin que la ville puisse agir imm\u00e9diatement apr\u00e8s l'adoption de la loi par le gouvernement du Land.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"z5ee\" style=\"background:var(--color-header-middle-bg);color:var(--color-content-heading);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-z5ee\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">D\u00e9cision sur les terrains \u00e0 b\u00e2tir pour des logements socialement et climatiquement adapt\u00e9s<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-z5ee\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Avec la nouvelle d\u00e9cision sur les terrains \u00e0 b\u00e2tir, nous avons \u00e9tabli des lignes directrices claires pour un d\u00e9veloppement urbain socialement \u00e9quitable et respectueux du climat. Les d\u00e9cisions relatives \u00e0 l'utilisation sociale des sols, au droit de superficie, \u00e0 l'attribution de concepts et \u00e0 la construction de logements subventionn\u00e9s seront regroup\u00e9es dans un cadre unique. \u00c0 l'avenir: Les nouveaux terrains \u00e0 b\u00e2tir pour le logement ne sont d\u00e9clar\u00e9s que si au moins 50 % de la surface est entre les mains de la ville ou est transf\u00e9r\u00e9e. En principe, une densit\u00e9 minimale de 80 unit\u00e9s d'habitation par hectare doit s'appliquer, pour autant que la typologie de l'espace urbain et la structure de l'habitat n'aient pas chang\u00e9. Il en r\u00e9sulte une s\u00e9curit\u00e9 de planification, des logements abordables et un d\u00e9veloppement urbain compact et \u00e9conome en ressources, un outil efficace pour lutter contre l\u2019augmentation des loyers et l\u2019occupation des sols.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"d70c\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-d70c\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Une politique fonci\u00e8re active pour un logement d'int\u00e9r\u00eat g\u00e9n\u00e9ral<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-d70c\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nous, les VERTS, avons mis en place la politique fonci\u00e8re active de Wiesbaden. L'objectif est d'acqu\u00e9rir des terrains \u00e0 un stade pr\u00e9coce afin d'\u00e9viter la sp\u00e9culation et de permettre la construction de logements sociaux. Le sol n'est pas une marchandise, mais la base du bien commun. Gr\u00e2ce \u00e0 la propri\u00e9t\u00e9 urbaine, les surfaces peuvent \u00eatre utilis\u00e9es de mani\u00e8re cibl\u00e9e pour des logements abordables, des infrastructures sociales ou la protection du climat. Ainsi, la ville reste capable d'agir et peut d\u00e9cider elle-m\u00eame de l'utilisation et de l'attribution. Ce mod\u00e8le, qui a fait ses preuves dans des villes telles qu\u2019Ulm ou M\u00fcnster, renforce la capacit\u00e9 d\u2019action des collectivit\u00e9s locales, garantit des logements abordables \u00e0 long terme et assure un d\u00e9veloppement urbain durable et socialement \u00e9quilibr\u00e9.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"o85f\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-o85f\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Davantage de logements b\u00e9n\u00e9ficiant d'une aide sociale<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-o85f\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">La soci\u00e9t\u00e9 de construction de logements GWW, une soci\u00e9t\u00e9 de participation municipale de la ville de Wiesbaden, a pour la premi\u00e8re fois atteint un parc de plus de 14 000 logements et renforce ainsi le logement abordable et d'int\u00e9r\u00eat g\u00e9n\u00e9ral \u00e0 Wiesbaden.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Des exemples tels que le quartier de Carinthie, le quartier de Sch\u00f6nau ou le projet Kastel-Housing montrent comment la politique communale fa\u00e7onne activement le d\u00e9veloppement des quartiers: Avec les r\u00e8gles du jeu que nous, les VERTS, avons initi\u00e9es de mani\u00e8re d\u00e9terminante pour le d\u00e9veloppement durable des quartiers (<\/span><a href=\"https:\/\/www.wiesbaden.de\/medien\/downloads\/leben-in-wiesbaden\/amt-61\/staedtebau\/Uebersicht-der-Spielregeln.pdf\"><span style=\"font-weight: 400;\">LINK<\/span><\/a><span style=\"font-weight: 400;\">) veillera \u00e0 ce que les nouveaux quartiers r\u00e9sidentiels soient non seulement socialement mixtes, adapt\u00e9s \u00e0 la famille et \u00e0 l\u2019\u00e2ge, mais aussi construits de mani\u00e8re efficace sur le plan \u00e9nerg\u00e9tique et \u00e9conome en ressources, et int\u00e8grent dans la planification des infrastructures vertes, des espaces verts urbains optimis\u00e9s pour le climat, une gestion sensible de l\u2019eau, des \u00e9nergies renouvelables et une nouvelle mobilit\u00e9. Wiesbaden allie ainsi un logement abordable, la justice sociale et la protection du climat dans des quartiers dynamiques et porteurs d'avenir.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"k97f\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-k97f\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Modes de construction innovants et projets de logements collectifs<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-k97f\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Dans des projets tels que Bierstadt-Nord, des appartements modernes dans une construction hybride en bois respectueuse du climat avec des surfaces communes et une occupation socialement \u00e9quilibr\u00e9e sont cr\u00e9\u00e9s.Le quartier garantira des logements abordables \u00e0 long terme gr\u00e2ce \u00e0 un mod\u00e8le de droit de superficie. \u00c0 Erbenheim-S\u00fcd, 33 appartements ont \u00e9t\u00e9 construits avec des unit\u00e9s adapt\u00e9es \u00e0 l'\u00e2ge et une cr\u00e8che, le b\u00e2timent est con\u00e7u comme une maison \u00e0 courant unique avec une installation photovolta\u00efque \u00e9conome en \u00e9nergie. Tous les projets associent les normes \u00e9cologiques, les espaces communs et la responsabilit\u00e9 sociale.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"ia9d\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-ia9d\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Logements d\u2019apprentis et d\u2019entreprises \u2013 logements cibl\u00e9s pour les professionnels<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-ia9d\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Gr\u00e2ce \u00e0 la construction d'appartements d'affaires dans la Herderstra\u00dfe, \u00e0 un projet pilote de logements pour apprentis et \u00e0 la construction d'appartements d'entreprise sur le site des cliniques Helios Dr. Horst Schmidt (HSK) par la GWW, nous assurons des logements abordables pour des groupes professionnels importants, favorisons la fid\u00e9lisation des travailleurs qualifi\u00e9s et d\u00e9montrons que la ville de Wiesbaden r\u00e9pond strat\u00e9giquement aux besoins du march\u00e9 du travail.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"hbb9\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-hbb9\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">D\u00e9veloppement urbain strat\u00e9gique et logements d'int\u00e9r\u00eat g\u00e9n\u00e9ral s\u00e9curis\u00e9s<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-hbb9\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">La SEG a pos\u00e9 des jalons importants pour Wiesbaden: Avec l'achat de la tour rouge, l'influence urbaine sur les logements a \u00e9t\u00e9 assur\u00e9e et un signal a \u00e9t\u00e9 donn\u00e9 en faveur d'un d\u00e9veloppement urbain d'int\u00e9r\u00eat g\u00e9n\u00e9ral. L'ancien American Arms Hotel (Kaiserhof) a \u00e9t\u00e9 transform\u00e9 en un quartier r\u00e9sidentiel moderne offrant un espace de vie de qualit\u00e9 et abordable dans un emplacement central. Ces projets renforcent la capacit\u00e9 d'action des communes, garantissent des logements \u00e0 long terme et contribuent au d\u00e9veloppement durable de la ville.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn us-btn-style_8 icon_atleft\" href=\"https:\/\/gruene-wiesbaden.de\/fr\/kommunalwahl\/#Kapitel1\"><i class=\"fas fa-chevron-circle-right\"><\/i><span class=\"w-btn-label\">Retour \u00e0 la vue d'ensemble<\/span><\/a><\/div><div class=\"w-separator size_large\"><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"Le logement est un droit de l'homme et un besoin \u00e9l\u00e9mentaire des gens. Une offre de logements abordables pour tous, de bonne qualit\u00e9 et en quantit\u00e9 suffisante, doit donc \u00eatre l'objectif de la politique du logement. Wiesbaden souffre \u00e9galement d'une grave p\u00e9nurie de logements abordables, tandis que l'augmentation des loyers et des prix des terrains aggrave les divisions sociales. Il nous faut donc \u00e0 Wiesbaden un...","protected":false},"author":1,"featured_media":1519,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1329","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kapitel-1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wohnen - B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gruene-wiesbaden.de\/fr\/wohnen\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wohnen - B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gruene-wiesbaden.de\/fr\/wohnen\/\" \/>\n<meta property=\"og:site_name\" content=\"B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gruene.wi\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-09T21:45:46+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T22:09:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.6-Wohnen-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1920\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#\\\/schema\\\/person\\\/6785c34779159cd4fd86886bb097afe9\"},\"headline\":\"Wohnen\",\"datePublished\":\"2025-11-09T21:45:46+00:00\",\"dateModified\":\"2026-04-08T22:09:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/\"},\"wordCount\":3152,\"publisher\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1.6-Wohnen-scaled.jpg\",\"articleSection\":[\"Kapitel 1\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/\",\"url\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/\",\"name\":\"Wohnen - B\u00dcNDNIS 90\\\/DIE GR\u00dcNEN Wiesbaden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1.6-Wohnen-scaled.jpg\",\"datePublished\":\"2025-11-09T21:45:46+00:00\",\"dateModified\":\"2026-04-08T22:09:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1.6-Wohnen-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1.6-Wohnen-scaled.jpg\",\"width\":2560,\"height\":1920},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wohnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wohnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#website\",\"url\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/\",\"name\":\"DIE GR\u00dcNEN Wiesbaden\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#organization\",\"name\":\"DIE GR\u00dcNEN Wiesbaden\",\"url\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gruene-wiesbaden-fuer-europa.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Machen-was-zaehlt-5.png\",\"contentUrl\":\"https:\\\/\\\/gruene-wiesbaden-fuer-europa.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Machen-was-zaehlt-5.png\",\"width\":1772,\"height\":1772,\"caption\":\"DIE GR\u00dcNEN Wiesbaden\"},\"image\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gruene.wi\",\"https:\\\/\\\/instagram.com\\\/gruene_wi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#\\\/schema\\\/person\\\/6785c34779159cd4fd86886bb097afe9\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/gruene-wiesbaden-fuer-europa.de\"],\"url\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/fr\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wohnen - B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gruene-wiesbaden.de\/fr\/wohnen\/","og_locale":"fr_FR","og_type":"article","og_title":"Wohnen - B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden","og_url":"https:\/\/gruene-wiesbaden.de\/fr\/wohnen\/","og_site_name":"B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden","article_publisher":"https:\/\/www.facebook.com\/gruene.wi","article_published_time":"2025-11-09T21:45:46+00:00","article_modified_time":"2026-04-08T22:09:17+00:00","og_image":[{"width":2560,"height":1920,"url":"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.6-Wohnen-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"admin","Dur\u00e9e de lecture estim\u00e9e":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gruene-wiesbaden.de\/wohnen\/#article","isPartOf":{"@id":"https:\/\/gruene-wiesbaden.de\/wohnen\/"},"author":{"name":"admin","@id":"https:\/\/gruene-wiesbaden.de\/#\/schema\/person\/6785c34779159cd4fd86886bb097afe9"},"headline":"Wohnen","datePublished":"2025-11-09T21:45:46+00:00","dateModified":"2026-04-08T22:09:17+00:00","mainEntityOfPage":{"@id":"https:\/\/gruene-wiesbaden.de\/wohnen\/"},"wordCount":3152,"publisher":{"@id":"https:\/\/gruene-wiesbaden.de\/#organization"},"image":{"@id":"https:\/\/gruene-wiesbaden.de\/wohnen\/#primaryimage"},"thumbnailUrl":"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.6-Wohnen-scaled.jpg","articleSection":["Kapitel 1"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/gruene-wiesbaden.de\/wohnen\/","url":"https:\/\/gruene-wiesbaden.de\/wohnen\/","name":"Wohnen - B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden","isPartOf":{"@id":"https:\/\/gruene-wiesbaden.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gruene-wiesbaden.de\/wohnen\/#primaryimage"},"image":{"@id":"https:\/\/gruene-wiesbaden.de\/wohnen\/#primaryimage"},"thumbnailUrl":"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.6-Wohnen-scaled.jpg","datePublished":"2025-11-09T21:45:46+00:00","dateModified":"2026-04-08T22:09:17+00:00","breadcrumb":{"@id":"https:\/\/gruene-wiesbaden.de\/wohnen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gruene-wiesbaden.de\/wohnen\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/gruene-wiesbaden.de\/wohnen\/#primaryimage","url":"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.6-Wohnen-scaled.jpg","contentUrl":"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.6-Wohnen-scaled.jpg","width":2560,"height":1920},{"@type":"BreadcrumbList","@id":"https:\/\/gruene-wiesbaden.de\/wohnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gruene-wiesbaden.de\/"},{"@type":"ListItem","position":2,"name":"Wohnen"}]},{"@type":"WebSite","@id":"https:\/\/gruene-wiesbaden.de\/#website","url":"https:\/\/gruene-wiesbaden.de\/","name":"DIE GR\u00dcNEN Wiesbaden","description":"","publisher":{"@id":"https:\/\/gruene-wiesbaden.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gruene-wiesbaden.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/gruene-wiesbaden.de\/#organization","name":"DIE GR\u00dcNEN Wiesbaden","url":"https:\/\/gruene-wiesbaden.de\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/gruene-wiesbaden.de\/#\/schema\/logo\/image\/","url":"https:\/\/gruene-wiesbaden-fuer-europa.de\/wp-content\/uploads\/2024\/04\/Machen-was-zaehlt-5.png","contentUrl":"https:\/\/gruene-wiesbaden-fuer-europa.de\/wp-content\/uploads\/2024\/04\/Machen-was-zaehlt-5.png","width":1772,"height":1772,"caption":"DIE GR\u00dcNEN Wiesbaden"},"image":{"@id":"https:\/\/gruene-wiesbaden.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gruene.wi","https:\/\/instagram.com\/gruene_wi"]},{"@type":"Person","@id":"https:\/\/gruene-wiesbaden.de\/#\/schema\/person\/6785c34779159cd4fd86886bb097afe9","name":"admin","sameAs":["http:\/\/gruene-wiesbaden-fuer-europa.de"],"url":"https:\/\/gruene-wiesbaden.de\/fr\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/gruene-wiesbaden.de\/fr\/wp-json\/wp\/v2\/posts\/1329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gruene-wiesbaden.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gruene-wiesbaden.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gruene-wiesbaden.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gruene-wiesbaden.de\/fr\/wp-json\/wp\/v2\/comments?post=1329"}],"version-history":[{"count":10,"href":"https:\/\/gruene-wiesbaden.de\/fr\/wp-json\/wp\/v2\/posts\/1329\/revisions"}],"predecessor-version":[{"id":2371,"href":"https:\/\/gruene-wiesbaden.de\/fr\/wp-json\/wp\/v2\/posts\/1329\/revisions\/2371"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gruene-wiesbaden.de\/fr\/wp-json\/wp\/v2\/media\/1519"}],"wp:attachment":[{"href":"https:\/\/gruene-wiesbaden.de\/fr\/wp-json\/wp\/v2\/media?parent=1329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gruene-wiesbaden.de\/fr\/wp-json\/wp\/v2\/categories?post=1329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gruene-wiesbaden.de\/fr\/wp-json\/wp\/v2\/tags?post=1329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}