{"id":1333,"date":"2025-11-09T23:48:01","date_gmt":"2025-11-09T21:48:01","guid":{"rendered":"https:\/\/gruene-wiesbaden.de\/?p=1333"},"modified":"2026-04-09T00:13:49","modified_gmt":"2026-04-08T22:13:49","slug":"kitaplaetze-und-ganztagsbetreuung","status":"publish","type":"post","link":"https:\/\/gruene-wiesbaden.de\/es\/kitaplaetze-und-ganztagsbetreuung\/","title":{"rendered":"Plazas de guarder\u00eda y guarder\u00edas durante todo el d\u00eda"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium with_img\"><div class=\"l-section-img\" role=\"img\" data-img-width=\"1080\" data-img-height=\"800\" style=\"background-image: url(https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/neuer-Verlauf-gruene-wiesbaden.de_-2-e1762709402177.png);\"><\/div><div class=\"l-section-overlay\" style=\"background:var(--color-header-top-transparent-bg)\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><h1 class=\"w-post-elm post_title us_custom_a574d586 has_text_color entry-title\">Plazas de guarder\u00eda y guarder\u00edas durante todo el d\u00eda<\/h1><div class=\"w-separator size_medium\"><\/div><div class=\"g-cols wpb_row via_grid cols_2-1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column us_custom_8b3d6790 has_text_color\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">La educaci\u00f3n de la primera infancia y la atenci\u00f3n confiable son cruciales para la igualdad de oportunidades, la familiaridad y el futuro de nuestra ciudad. Todos los ni\u00f1os tienen derecho a la mejor educaci\u00f3n y atenci\u00f3n posible desde el principio. La educaci\u00f3n de la primera infancia es la base para la igualdad de oportunidades y la participaci\u00f3n social. Al mismo tiempo, un cuidado infantil fiable permite a los padres y a los padres solteros conciliar mejor la familia y el trabajo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Queremos continuar desarrollando Wiesbaden en una ciudad amigable para los ni\u00f1os y la familia, donde cada ni\u00f1o reciba las mejores oportunidades de inicio posibles. Una buena infraestructura en las guarder\u00edas y la atenci\u00f3n durante todo el d\u00eda es un requisito b\u00e1sico para esto. Estamos comprometidos a crearlos.<\/span><\/p>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn us-btn-style_8 icon_atleft\" href=\"https:\/\/gruene-wiesbaden.de\/es\/kommunalwahl\/#Kapitel1\"><i class=\"fas fa-chevron-circle-right\"><\/i><span class=\"w-btn-label\">Volver a la descripci\u00f3n general<\/span><\/a><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img decoding=\"async\" width=\"1706\" height=\"2560\" src=\"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" loading=\"lazy\" srcset=\"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg 1706w, https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.7-Kitaplaetze-und-Ganztagsbetreuung-267x400.jpg 267w, https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.7-Kitaplaetze-und-Ganztagsbetreuung-400x600.jpg 400w\" sizes=\"auto, (max-width: 1706px) 100vw, 1706px\" \/><\/div><\/div><div class=\"w-separator size_small\"><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h1>Lo que una buena infraestructura de guarder\u00eda y cuidado durante todo el d\u00eda significa para nosotros<\/h1>\n<\/div><\/div><div class=\"w-separator size_large\"><\/div><div class=\"g-cols wpb_row via_grid cols_3 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-middle-bg);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Igualdad de oportunidades y participaci\u00f3n<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">Todos los ni\u00f1os tienen acceso a cuidados de calidad, incluidas guarder\u00edas y escuelas, y los servicios de traducci\u00f3n digital promueven la igualdad de oportunidades para todos.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-transparent-text);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Educaci\u00f3n desde el principio<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">Conceptos pedag\u00f3gicos de alta calidad, especialistas calificados y salas modernas aseguran oportunidades de aprendizaje y desarrollo para todos los ni\u00f1os.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-transparent-text);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Amabilidad familiar<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">Las guarder\u00edas no contributivas o reducidas, las guarder\u00edas durante todo el d\u00eda, las ofertas de vacaciones y KiEZe (Centros para padres de ni\u00f1os) facilitan la conciliaci\u00f3n de la vida laboral y familiar.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"g-cols wpb_row via_grid cols_3 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\" style=\"--columns-gap:3rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-middle-bg);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Sostenibilidad e infraestructura sostenible<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">Las renovaciones eficientes desde el punto de vista energ\u00e9tico, los conceptos de construcci\u00f3n respetuosos con el clima y las zonas exteriores modernas crean entornos de aprendizaje saludables y que ahorran recursos.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-transparent-text);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Innovaci\u00f3n y participaci\u00f3n digital<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">Las herramientas digitales como Kids Fox mejoran la comunicaci\u00f3n, la organizaci\u00f3n y la accesibilidad, y promueven el multiling\u00fcismo.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-iconbox us_custom_8b3d6790 has_text_color iconpos_left style_default color_custom align_left\"><div class=\"w-iconbox-icon\" style=\"font-size:2rem;--icon-color:#Ffffff;--icon-bg-color:var(--color-header-transparent-text);\"><i class=\"fas fa-layer-group\"><\/i><\/div><div class=\"w-iconbox-meta\"><h4 class=\"w-iconbox-title\" style=\"font-size:1.5rem;\">Orientaci\u00f3n y calidad del distrito<\/h4><div class=\"w-iconbox-text\"><p><span style=\"font-weight: 400;\">KiEZe y las guarder\u00edas locales fortalecen las redes locales, promueven la comunidad y aseguran continuamente un apoyo de alta calidad a trav\u00e9s de capacitaci\u00f3n adicional y est\u00e1ndares de calidad.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn us-btn-style_8 icon_atleft\" href=\"https:\/\/gruene-wiesbaden.de\/es\/kommunalwahl\/#Kapitel1\"><i class=\"fas fa-chevron-circle-right\"><\/i><span class=\"w-btn-label\">Volver a la descripci\u00f3n general<\/span><\/a><\/div><div class=\"w-separator size_medium\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto with_img\"><div class=\"l-section-img\" role=\"img\" data-img-width=\"1706\" data-img-height=\"2560\" style=\"background-image: url(https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg);background-repeat: no-repeat;\"><\/div><div class=\"l-section-overlay\" style=\"background:var(--color-header-top-transparent-bg)\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_middle type_default stacking_default\" style=\"--columns-gap:1rem;\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-separator size_large\"><\/div><div class=\"wpb_text_column background_inside_text\"><div class=\"wpb_wrapper\"><h1>Lo que queremos hacer espec\u00edficamente en esta \u00e1rea<\/h1>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-tabs us_custom_42d693a0 has_text_color style_default switch_click accordion has_scrolling\" style=\"--sections-title-size:1.4rem\"><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section has_text_color\" id=\"r32e\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-r32e\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Hacer que el cuidado de ni\u00f1os no sea contributivo<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-r32e\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Trabajamos con el Estado para garantizar que las guarder\u00edas infantiles sean gratuitas. Hasta entonces, queremos continuar con el esquema de contribuci\u00f3n urbana existente, que reduce las contribuciones para las familias numerosas y exime de contribuciones a las familias de bajos ingresos.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"q44f\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-q44f\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Fuerte infraestructura de guarder\u00eda para el futuro de nuestra ciudad<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-q44f\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">La calidad educativa comienza a una edad temprana. GR\u00dcNEN est\u00e1 comprometido con la expansi\u00f3n basada en las necesidades de las guarder\u00edas en Wiesbaden, con conceptos de atenci\u00f3n de alta calidad y suficientes especialistas pedag\u00f3gicos que merecen condiciones de trabajo justas. Al hacerlo, estamos mirando espec\u00edficamente a las \u00e1reas urbanas con una situaci\u00f3n cr\u00edtica de suministro. En otros distritos, sin embargo, ahora hay un exceso de oferta. Por lo tanto, es necesario un endurecimiento de la estrategia de expansi\u00f3n del jard\u00edn de infancia, con la pretensi\u00f3n de utilizar los recursos financieros m\u00e1s espec\u00edficamente y permitir una mayor flexibilidad en las necesidades cambiantes (por ejemplo, U3 frente al \u00e1rea elemental). Esto requiere una inclusi\u00f3n integral de par\u00e1metros de planificaci\u00f3n como la tasa de natalidad y el cambio en la demanda de plazas de guarder\u00eda a trav\u00e9s de nuevos proyectos de construcci\u00f3n.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"a56e\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-a56e\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Continuar la ofensiva de construcci\u00f3n y renovaci\u00f3n respetuosa con el clima<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-a56e\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Queremos crear guarder\u00edas adicionales a trav\u00e9s de un programa de construcci\u00f3n acelerado y conceptos innovadores de habitaciones. Las instalaciones existentes se est\u00e1n renovando y modernizando energ\u00e9ticamente para proporcionar a nuestros ni\u00f1os un entorno de aprendizaje saludable y, al mismo tiempo, alcanzar los objetivos de protecci\u00f3n del clima. Especialmente con la oferta de cuidado durante todo el d\u00eda en las guarder\u00edas y la expansi\u00f3n de las escuelas durante todo el d\u00eda, un edificio y un \u00e1rea al aire libre, que ofrecen una buena calidad de estad\u00eda incluso en d\u00edas calurosos, son importantes.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"s691\" style=\"background:var(--color-header-middle-bg);color:var(--color-content-heading);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-s691\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Promover instalaciones sin barreras e inclusivas<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-s691\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nos aseguramos de que haya suficientes guarder\u00edas y escuelas sin barreras e inclusivas en nuestra ciudad.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"o7ae\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-o7ae\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Ampl\u00ede las ofertas durante todo el d\u00eda en todos los \u00e1mbitos<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-o7ae\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">El \u00abPacto de todo el d\u00eda\u00bb es un modelo que ofrece asistencia voluntaria de las 7.30 a las 17.00 horas en las escuelas primarias y los niveles primarios de las escuelas con necesidades especiales cinco d\u00edas a la semana. En Wiesbaden, once escuelas participan actualmente en el pacto de todo el d\u00eda, con un total de 2 679 ni\u00f1os (hasta agosto de 2024). A partir del a\u00f1o escolar 2026\/27, existe un derecho legal a la atenci\u00f3n a tiempo completo para los ni\u00f1os de la escuela primaria. Queremos invertir en una oferta fiable durante todo el d\u00eda en todas las escuelas primarias de Wiesbaden. Con este fin, queremos crear las premisas necesarias, promover equipos multiprofesionales y apoyar el desarrollo de conceptos pedag\u00f3gicos que combinen significativamente el aprendizaje y el tiempo de ocio y permitan que todos los ni\u00f1os tengan igualdad de oportunidades educativas.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"f8cb\" style=\"background:var(--color-header-middle-bg);color:var(--color-header-middle-text);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-f8cb\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Alimentos regionales ecol\u00f3gicos<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-f8cb\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Convertimos el servicio de catering en todas las guarder\u00edas y escuelas municipales en al menos un 50 por ciento de productos biorregionales. A trav\u00e9s de la cooperaci\u00f3n con los productores locales, creamos cadenas de suministro cortas e introducimos un sistema de etiquetado transparente que ense\u00f1a a los ni\u00f1os sobre la nutrici\u00f3n sostenible de una manera l\u00fadica. Tambi\u00e9n estamos comprometidos a ofrecer al menos una alternativa vegana completa para ofrecer a los ni\u00f1os con diferentes dietas o alergias una opci\u00f3n adecuada.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"p9e8\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-p9e8\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Comunicaci\u00f3n digital y multiling\u00fcismo en guarder\u00edas y escuelas<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-p9e8\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Nos comprometemos a garantizar que todas las familias tengan igualdad de acceso a la educaci\u00f3n y la atenci\u00f3n, independientemente del idioma y el origen. Desde 2025, la ciudad de Wiesbaden ha apoyado la aplicaci\u00f3n Kids Fox en las 42 guarder\u00edas municipales, que apoya a los padres y al personal de la guarder\u00eda en la comunicaci\u00f3n y la organizaci\u00f3n y traduce autom\u00e1ticamente el contenido a 27 idiomas. Tambi\u00e9n queremos promover soluciones digitales para las escuelas: Con Schoolfox y aplicaciones similares, los maestros, estudiantes y padres deben poder comunicarse entre s\u00ed de manera eficiente y sin barreras. Estamos revisando una entrega centralizada a trav\u00e9s del Media Center para garantizar un uso consistente, el cumplimiento de la protecci\u00f3n de datos y la diversidad ling\u00fc\u00edstica. De esta manera, combinamos la innovaci\u00f3n digital con la igualdad de oportunidades y hacemos que el acceso a la educaci\u00f3n sea m\u00e1s f\u00e1cil y transparente para todas las familias.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"ib07\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-ib07\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Ampliaci\u00f3n de los centros para padres e hijos (KiEZe)<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-ib07\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Con el KinderElternZentren (KiEZe), las familias se fortalecen directamente en sus distritos. Desde hace varios a\u00f1os, los KiEZe de Wiesbaden \u2014por ejemplo, en Klarenthal, Schelmengraben, Westend y Biebrich\u2014 ofrecen asesoramiento, educaci\u00f3n y reuniones. Estos sirven como puntos de contacto de bajo umbral en los distritos y ofrecen guarder\u00edas flexibles, cafeter\u00edas para padres y asesoramiento educativo de una sola fuente; se trata de una oferta importante, especialmente para las familias monoparentales y las familias en situaciones dif\u00edciles. Las guarder\u00edas de la red KiEZe, los servicios sociales y las iniciativas vecinales promueven as\u00ed la comunidad y la igualdad de oportunidades. Los Verdes apoyamos este concepto desde el principio y estamos comprometidos a fortalecer a\u00fan m\u00e1s el KiEZe existente y expandirlo a otros distritos.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"zc1f\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-zc1f\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Reforzar la participaci\u00f3n de los padres<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-zc1f\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">La buena cooperaci\u00f3n entre los padres y las guarder\u00edas promueve el inter\u00e9s superior del ni\u00f1o y la calidad de la atenci\u00f3n. Adem\u00e1s de las reuniones individuales y las veladas con los padres, la participaci\u00f3n en los consejos consultivos de los padres, tambi\u00e9n en todas las instituciones, es un elemento importante de la participaci\u00f3n. Por lo tanto, queremos fortalecer el trabajo de los consejos asesores de los padres en las guarder\u00edas, as\u00ed como su red en toda la ciudad.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn us-btn-style_8 icon_atleft\" href=\"https:\/\/gruene-wiesbaden.de\/es\/kommunalwahl\/#Kapitel1\"><i class=\"fas fa-chevron-circle-right\"><\/i><span class=\"w-btn-label\">Volver a la descripci\u00f3n general<\/span><\/a><\/div><div class=\"w-separator size_large\"><\/div><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h1>Lo que ya hemos logrado<\/h1>\n<\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-tabs us_custom_42d693a0 has_text_color style_default switch_click accordion has_scrolling\" style=\"--sections-title-size:1.4rem\"><div class=\"w-tabs-sections titles-align_none icon_chevron cpos_right\"><div class=\"w-tabs-section has_text_color\" id=\"hef4\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-hef4\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">La expansi\u00f3n de Kita avanz\u00f3 con \u00e9xito<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-hef4\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Desde 2022, hemos ampliado significativamente la guarder\u00eda en Wiesbaden: En el a\u00f1o de guarder\u00eda 2024\/25, hab\u00eda 10 308 plazas disponibles, 227 m\u00e1s que en el a\u00f1o anterior, y el n\u00famero de ni\u00f1os en Wiesbaden disminuy\u00f3 (2020\/21 11,062, 2024\/25 10,912). En el \u00e1rea U3, el espacio disponible es de 37.7% en 2020\/21 a 41.1% en 2024\/25 y en el rango elemental de 90% en 2020\/21 a 94,4%aumento en 2024\/2025. Esto permiti\u00f3 que m\u00e1s familias combinaran el trabajo y el cuidado de los ni\u00f1os.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"k00e\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-k00e\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Apertura de nuevos jardines de infancia<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-k00e\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Se han creado nuevas instalaciones, especialmente en \u00e1reas de nueva construcci\u00f3n como el barrio de Carintia. Por lo tanto, se ha mejorado espec\u00edficamente la oferta en los distritos de alto crecimiento.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"g128\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-g128\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Introducci\u00f3n de la aplicaci\u00f3n Kita Kids Fox con funci\u00f3n de traducci\u00f3n<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-g128\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Desde 2025, la aplicaci\u00f3n Kids Fox se ha introducido en las 42 guarder\u00edas urbanas. Esto apoya a los padres y al personal de la guarder\u00eda en la comunicaci\u00f3n y la organizaci\u00f3n. La aplicaci\u00f3n ofrece una funci\u00f3n de traducci\u00f3n autom\u00e1tica en 27 idiomas.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"o256\" style=\"background:var(--color-header-middle-bg);color:var(--color-content-heading);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-o256\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Ampliaci\u00f3n de la atenci\u00f3n durante todo el d\u00eda en las escuelas<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-o256\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Ya 62 % Los ni\u00f1os de la escuela primaria ahora est\u00e1n aprovechando la atenci\u00f3n de la tarde. Se trata de un paso importante hacia la aplicaci\u00f3n del derecho legal a la atenci\u00f3n a tiempo completo.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"k36f\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-k36f\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Mejora de la calidad de la atenci\u00f3n<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-k36f\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Se han aplicado medidas para el desarrollo de la calidad en las guarder\u00edas y las actividades durante todo el d\u00eda. Esto incluye una mayor formaci\u00f3n de los profesionales pedag\u00f3gicos, la introducci\u00f3n de normas de calidad vinculantes y la evaluaci\u00f3n peri\u00f3dica de los centros asistenciales. Esto asegura que los ni\u00f1os sean apoyados y cuidados de manera confiable e individual de una manera amigable para la familia. Los padres pueden confiar en ofertas de alta calidad, y el cuidado apoya el desarrollo del ni\u00f1o de la mejor manera posible.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><div class=\"w-tabs-section has_text_color\" id=\"o48b\" style=\"background:var(--color-header-transparent-text);color:var(--color-header-top-text-hover);\"><button class=\"w-tabs-section-header\" aria-controls=\"content-o48b\" aria-expanded=\"false\"><div class=\"w-tabs-section-title\">Servicios de atenci\u00f3n de vacaciones ampliados y mejorados<\/div><div class=\"w-tabs-section-control\"><\/div><\/button><div  class=\"w-tabs-section-content\" id=\"content-o48b\"><div class=\"w-tabs-section-content-h i-cf\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p><span style=\"font-weight: 400;\">Los servicios de atenci\u00f3n navide\u00f1a para ni\u00f1os y adolescentes se han ampliado considerablemente. A trav\u00e9s de la cooperaci\u00f3n de la ciudad con varios socios, se han creado programas adicionales que satisfacen las necesidades de las familias. Proyectos como los juegos de vacaciones de verano en el Parque Natural Cyperus, por ejemplo, ofrecieron a los ni\u00f1os la oportunidad de pasar sus vacaciones en un entorno natural. Adem\u00e1s, los Verdes estamos comprometidos a integrar las ofertas de vacaciones en el programa de vacaciones urbanas para garantizar una mejor visi\u00f3n general y accesibilidad para todas las familias, independientemente de sus ingresos o situaci\u00f3n de vida.<\/span><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"w-separator size_medium\"><\/div><div class=\"w-btn-wrapper align_left\"><a class=\"w-btn us-btn-style_8 icon_atleft\" href=\"https:\/\/gruene-wiesbaden.de\/es\/kommunalwahl\/#Kapitel1\"><i class=\"fas fa-chevron-circle-right\"><\/i><span class=\"w-btn-label\">Volver a la descripci\u00f3n general<\/span><\/a><\/div><div class=\"w-separator size_large\"><\/div><\/div><\/div><\/div><\/div><\/section>","protected":false},"excerpt":{"rendered":"La educaci\u00f3n de la primera infancia y la atenci\u00f3n confiable son cruciales para la igualdad de oportunidades, la amistad familiar y el futuro de nuestra ciudad. Todos los ni\u00f1os tienen derecho a la mejor educaci\u00f3n y atenci\u00f3n posible desde el principio. La educaci\u00f3n de la primera infancia es la base para la igualdad de oportunidades y la participaci\u00f3n social. Al mismo tiempo, el cuidado confiable de los ni\u00f1os permite a los padres y padres solteros mejorar su familia y sus carreras.","protected":false},"author":1,"featured_media":1485,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[14],"tags":[],"class_list":["post-1333","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-kapitel-1"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kitapl\u00e4tze und Ganztagsbetreuung - B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gruene-wiesbaden.de\/es\/kitaplaetze-und-ganztagsbetreuung\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kitapl\u00e4tze und Ganztagsbetreuung - B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gruene-wiesbaden.de\/es\/kitaplaetze-und-ganztagsbetreuung\/\" \/>\n<meta property=\"og:site_name\" content=\"B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gruene.wi\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-09T21:48:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-04-08T22:13:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1706\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#\\\/schema\\\/person\\\/6785c34779159cd4fd86886bb097afe9\"},\"headline\":\"Kitapl\u00e4tze und Ganztagsbetreuung\",\"datePublished\":\"2025-11-09T21:48:01+00:00\",\"dateModified\":\"2026-04-08T22:13:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/\"},\"wordCount\":2478,\"publisher\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg\",\"articleSection\":[\"Kapitel 1\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/\",\"url\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/\",\"name\":\"Kitapl\u00e4tze und Ganztagsbetreuung - B\u00dcNDNIS 90\\\/DIE GR\u00dcNEN Wiesbaden\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg\",\"datePublished\":\"2025-11-09T21:48:01+00:00\",\"dateModified\":\"2026-04-08T22:13:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/wp-content\\\/uploads\\\/2025\\\/11\\\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg\",\"width\":1706,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/kitaplaetze-und-ganztagsbetreuung\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kitapl\u00e4tze und Ganztagsbetreuung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#website\",\"url\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/\",\"name\":\"DIE GR\u00dcNEN Wiesbaden\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#organization\",\"name\":\"DIE GR\u00dcNEN Wiesbaden\",\"url\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gruene-wiesbaden-fuer-europa.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Machen-was-zaehlt-5.png\",\"contentUrl\":\"https:\\\/\\\/gruene-wiesbaden-fuer-europa.de\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/Machen-was-zaehlt-5.png\",\"width\":1772,\"height\":1772,\"caption\":\"DIE GR\u00dcNEN Wiesbaden\"},\"image\":{\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gruene.wi\",\"https:\\\/\\\/instagram.com\\\/gruene_wi\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/#\\\/schema\\\/person\\\/6785c34779159cd4fd86886bb097afe9\",\"name\":\"admin\",\"sameAs\":[\"http:\\\/\\\/gruene-wiesbaden-fuer-europa.de\"],\"url\":\"https:\\\/\\\/gruene-wiesbaden.de\\\/es\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kitapl\u00e4tze und Ganztagsbetreuung - B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gruene-wiesbaden.de\/es\/kitaplaetze-und-ganztagsbetreuung\/","og_locale":"es_ES","og_type":"article","og_title":"Kitapl\u00e4tze und Ganztagsbetreuung - B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden","og_url":"https:\/\/gruene-wiesbaden.de\/es\/kitaplaetze-und-ganztagsbetreuung\/","og_site_name":"B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden","article_publisher":"https:\/\/www.facebook.com\/gruene.wi","article_published_time":"2025-11-09T21:48:01+00:00","article_modified_time":"2026-04-08T22:13:49+00:00","og_image":[{"width":1706,"height":2560,"url":"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg","type":"image\/jpeg"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"admin","Tiempo de lectura":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/#article","isPartOf":{"@id":"https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/"},"author":{"name":"admin","@id":"https:\/\/gruene-wiesbaden.de\/#\/schema\/person\/6785c34779159cd4fd86886bb097afe9"},"headline":"Kitapl\u00e4tze und Ganztagsbetreuung","datePublished":"2025-11-09T21:48:01+00:00","dateModified":"2026-04-08T22:13:49+00:00","mainEntityOfPage":{"@id":"https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/"},"wordCount":2478,"publisher":{"@id":"https:\/\/gruene-wiesbaden.de\/#organization"},"image":{"@id":"https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/#primaryimage"},"thumbnailUrl":"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg","articleSection":["Kapitel 1"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/","url":"https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/","name":"Kitapl\u00e4tze und Ganztagsbetreuung - B\u00dcNDNIS 90\/DIE GR\u00dcNEN Wiesbaden","isPartOf":{"@id":"https:\/\/gruene-wiesbaden.de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/#primaryimage"},"image":{"@id":"https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/#primaryimage"},"thumbnailUrl":"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg","datePublished":"2025-11-09T21:48:01+00:00","dateModified":"2026-04-08T22:13:49+00:00","breadcrumb":{"@id":"https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/#primaryimage","url":"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg","contentUrl":"https:\/\/gruene-wiesbaden.de\/wp-content\/uploads\/2025\/11\/1.7-Kitaplaetze-und-Ganztagsbetreuung-scaled.jpg","width":1706,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/gruene-wiesbaden.de\/kitaplaetze-und-ganztagsbetreuung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/gruene-wiesbaden.de\/"},{"@type":"ListItem","position":2,"name":"Kitapl\u00e4tze und Ganztagsbetreuung"}]},{"@type":"WebSite","@id":"https:\/\/gruene-wiesbaden.de\/#website","url":"https:\/\/gruene-wiesbaden.de\/","name":"DIE GR\u00dcNEN Wiesbaden","description":"","publisher":{"@id":"https:\/\/gruene-wiesbaden.de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gruene-wiesbaden.de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/gruene-wiesbaden.de\/#organization","name":"DIE GR\u00dcNEN Wiesbaden","url":"https:\/\/gruene-wiesbaden.de\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/gruene-wiesbaden.de\/#\/schema\/logo\/image\/","url":"https:\/\/gruene-wiesbaden-fuer-europa.de\/wp-content\/uploads\/2024\/04\/Machen-was-zaehlt-5.png","contentUrl":"https:\/\/gruene-wiesbaden-fuer-europa.de\/wp-content\/uploads\/2024\/04\/Machen-was-zaehlt-5.png","width":1772,"height":1772,"caption":"DIE GR\u00dcNEN Wiesbaden"},"image":{"@id":"https:\/\/gruene-wiesbaden.de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gruene.wi","https:\/\/instagram.com\/gruene_wi"]},{"@type":"Person","@id":"https:\/\/gruene-wiesbaden.de\/#\/schema\/person\/6785c34779159cd4fd86886bb097afe9","name":"admin","sameAs":["http:\/\/gruene-wiesbaden-fuer-europa.de"],"url":"https:\/\/gruene-wiesbaden.de\/es\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/gruene-wiesbaden.de\/es\/wp-json\/wp\/v2\/posts\/1333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gruene-wiesbaden.de\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gruene-wiesbaden.de\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gruene-wiesbaden.de\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/gruene-wiesbaden.de\/es\/wp-json\/wp\/v2\/comments?post=1333"}],"version-history":[{"count":8,"href":"https:\/\/gruene-wiesbaden.de\/es\/wp-json\/wp\/v2\/posts\/1333\/revisions"}],"predecessor-version":[{"id":2373,"href":"https:\/\/gruene-wiesbaden.de\/es\/wp-json\/wp\/v2\/posts\/1333\/revisions\/2373"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gruene-wiesbaden.de\/es\/wp-json\/wp\/v2\/media\/1485"}],"wp:attachment":[{"href":"https:\/\/gruene-wiesbaden.de\/es\/wp-json\/wp\/v2\/media?parent=1333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gruene-wiesbaden.de\/es\/wp-json\/wp\/v2\/categories?post=1333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gruene-wiesbaden.de\/es\/wp-json\/wp\/v2\/tags?post=1333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}